{"id":6903,"date":"2022-05-18T09:51:38","date_gmt":"2022-05-18T09:51:38","guid":{"rendered":"https:\/\/decoupled-hhg.local\/terms-conditions\/"},"modified":"2024-01-16T15:30:01","modified_gmt":"2024-01-16T15:30:01","slug":"terms-conditions","status":"publish","type":"page","link":"https:\/\/www.hhglobal.com\/it\/terms-conditions\/","title":{"rendered":"Terms + Conditions"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":41,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":"","_yoast_wpseo_focuskw":"","_yoast_wpseo_metadesc":"","_yoast_wpseo_linkdex":"","_yoast_wpseo_content_score":"","_yoast_wpseo_meta-robots-noindex":"","_yoast_wpseo_meta-robots-nofollow":"","inline_featured_image":[],"_genesis_block_theme_hide_title":false,"_cms_nav_minihome":"","_icl_lang_duplicate_of":"","_menu_item_classes":[],"_menu_item_menu_item_parent":"","_menu_item_object":"","_menu_item_object_id":"","_menu_item_orphaned":"","_menu_item_target":"","_menu_item_type":"","_menu_item_url":"","_menu_item_xfn":"","_seedprod_page":"","_seedprod_page_template_type":"","_seedprod_page_uuid":"","_top_nav_excluded":"","_wp_attachment_backup_sizes":[],"_wp_attachment_context":"","_wp_attachment_image_alt":"","_wp_old_date":"","_wpcode_auto_insert":"","_wpcode_auto_insert_number":"","_wpcode_library_id":"","_wpml_media_duplicate":"1","_wpml_media_featured":"1","_wpml_post_translation_editor_native":"","_wpml_word_count":"{\"total\":5,\"to_translate\":{\"zh-hans\":5,\"cs\":5,\"de\":5,\"ja\":5,\"pt-br\":5,\"es\":5}}","_yoast_wpseo_estimated-reading-time-minutes":["0"],"_yoast_wpseo_primary_category":"","_yoast_wpseo_primary_industry":"","_yoast_wpseo_primary_solution":"","_yoast_wpseo_primary_the_author":"","_yoast_wpseo_wordproof_timestamp":"","acfml_non_translatable_locations":[],"career_externalLink":"","career_featuredImage":"","career_title":"","casestudy_featuredImage":"","casestudy_title":"","infocallout_excerpt":"","infocallout_featuredImage":"","infocallout_title":"","jobTitle":"","language":"","name":"","profilePicture":"","wp-smpro-smush-data":[],"wp-smush-animated":"","wp-smush-ignore-bulk":"","wp-smush-lossy":"","wpml_media_processed":"","_wpcode_conditional_logic_enabled":"","_wpcode_location_extra":"","_wpcode_note":"","_wpcode_priority":"","_wpcode_shortcode_attributes":[],"footnotes":""},"class_list":["post-6903","page","type-page","status-publish","hentry","post","without-featured-image"],"acf":{"page_title":"Termini + Condizioni | HH Global","page_description":"","social_title":"","social_description":"","social_share_image":null,"modules":[{"acf_fc_layout":"hero","size":"medium","theme":"dark","choose_images":[{"image":6322}],"show_eyebrow":false,"eyebrow":"","title":"Termini e Condizioni","show_cta":false,"cta_url":"","cta_title":""},{"acf_fc_layout":"rich_content","scroll_to_link":"","container_background_color":"bg-white","content":"Alcuni dei termini e delle condizioni applicabili al tuo rapporto con il gruppo di societ\u00e0 HH Global dipendono dal fatto che tu sia un cliente o un fornitore del gruppo:\r\n\r\n<strong>Termini con i nostri clienti<\/strong>\r\nLa maggior parte dei nostri clienti ha firmato contratti con HH Associates Ltd. Se non \u00e8 stato concordato alcun contratto, forniremo beni e servizi sulla base dei nostri termini e condizioni standard. I prezzi\/modelli commerciali e gli eventuali livelli di servizio che possono essere applicati ai servizi forniti variano da ordine a ordine e saranno registrati in un preventivo\/ordine se non trattato in contratto.\r\n\r\n<a title=\"HH Global Client Standard Terms and Conditions - v1.2.pdf\" href=\"https:\/\/www.hhglobal.com\/wp-content\/uploads\/2022\/06\/ClientStandardTermsConditionsFeb2021.pdf\" target=\"_blank\" rel=\"noopener\" data-udi=\"umb:\/\/media\/eca25f8d6a4b4b9a9b1f7471bed4ad4d\">Termini e condizioni standard del cliente<\/a>\r\n\r\n<strong>Termini per i nostri fornitori<\/strong>\r\nLa stragrande maggioranza dei nostri fornitori stipula contratti con HH Global. Se non \u00e8 stato concordato alcun contratto con un fornitore, le {Link} Termini e condizioni generali di acquisto si applicano a tutti gli ordini effettuati da HH Global. Copie dei nostri documenti contrattuali sono disponibili in varie versioni bilingue e possono essere richieste a info@www.hhglobal.com.\r\n\r\n<strong>Termini per l'utilizzo del sito web<\/strong>\r\nI presenti termini e condizioni disciplinano l'utilizzo del sito Web di HH Global Group e il rapporto con il gruppo di societ\u00e0 HH Global Group. Si prega di consultarli con attenzione in quanto influenzano i diritti e le responsabilit\u00e0 ai sensi della legge. Se non si accettano questi Termini e condizioni, si prega di non registrarsi o utilizzare il sito della societ\u00e0. In caso di domande sui Termini e condizioni, contattare info@www.hhglobal.com.\r\n\r\nLa Societ\u00e0 mette a disposizione informazioni, materiali e prodotti su questo sito Web, soggetti ai seguenti termini e condizioni. Con l\u2019accesso a qualsiasi parte di questo sito, si riterr\u00e0 di aver accettato integralmente i presenti termini e condizioni. Potremmo aggiornare questi Termini e Condizioni di volta in volta per motivi legali o normativi o per consentire il corretto funzionamento del Sito della Societ\u00e0. Eventuali modifiche ti saranno comunicate tramite l'indirizzo email da te fornito al momento della registrazione o tramite apposito annuncio sul Sito della Societ\u00e0. Le modifiche si applicheranno all'utilizzo del Sito aziendale dopo che ne avremo dato avviso. Se non si desidera accettare i nuovi Termini e condizioni, non \u00e8 necessario continuare a utilizzare il Sito aziendale. Se continui a utilizzare il Sito aziendale dopo la data in cui la modifica entra in vigore, l'utilizzo del sito aziendale indica che accetti di essere vincolato dai nuovi Termini e condizioni.\r\n\r\n<strong>Accesso<\/strong>\r\nMentre la Societ\u00e0 si impegna a garantire che questo sito sia normalmente disponibile 24 ore al giorno, la Societ\u00e0 non sar\u00e0 responsabile se per qualsiasi motivo il sito non sar\u00e0 disponibile, in qualsiasi momento o in qualsivoglia periodo. L'accesso a questo sito pu\u00f2 essere sospeso temporaneamente o permanentemente e senza preavviso.\r\n\r\n<strong>Propriet\u00e0 intellettuale<\/strong>\r\nSalvo diversa indicazione, il copyright e qualsiasi altro diritto su tutto il materiale presenti su questo sito web sono di propriet\u00e0 della Societ\u00e0. Ad eccezione di quanto specificamente consentito in particolari aree di questo sito, nessuna delle informazioni su questo sito pu\u00f2 essere riprodotta, modificata, copiata o distribuita in qualsiasi forma o con qualsiasi mezzo senza previa autorizzazione scritta da parte della Societ\u00e0. Nessuna parte di questo sito pu\u00f2 essere riprodotta o memorizzata in qualsiasi altro sito Web o inclusa in qualsiasi sistema o servizio di recupero elettronico pubblico o privato senza la preventiva autorizzazione scritta della Societ\u00e0 e nessuna rinuncia sar\u00e0 valida se non in forma scritta e indirizzata direttamente all'interessato. I marchi, i loghi e i marchi di servizio visualizzati su questo sito sono di propriet\u00e0 della Societ\u00e0, del suo licenziante o di terzi. Non \u00e8 possibile utilizzare nessuno dei Marchi senza il previo consenso scritto della Societ\u00e0 o della terza parte proprietaria del relativo Marchio. Tutti i diritti non espressamente concessi in questi termini sono riservati.\r\n\r\n<strong>Responsabilit\u00e0<\/strong>\r\nMentre la Societ\u00e0 si impegna a garantire che le informazioni su questo sito siano corrette, nessuna garanzia, esplicita o implicita, viene fornita in merito alla loro accuratezza e la Societ\u00e0 non si assume alcuna responsabilit\u00e0 per errori o omissioni. La Societ\u00e0 non sar\u00e0 responsabile per eventuali danni derivanti da contratto, torto o altro dall'uso o dall'impossibilit\u00e0 di utilizzare questo sito, o qualsiasi materiale in esso contenuto, o da qualsiasi azione o decisione presa in conseguenza dell'utilizzo di questo sito o di qualsiasi tale materiale. Parte di questo sito contiene materiale inviato alla Societ\u00e0 da terzi. Tali terze parti sono responsabili di garantire che il materiale inviato per l'inclusione in questo sito sia conforme alla legge nazionale e straniera pertinente. La Societ\u00e0 non sar\u00e0 responsabile per eventuali errori, omissioni o inesattezze nel materiale e si riserva il diritto di omettere, sospendere o modificare qualsiasi materiale inviato. In caso di violazione dei presenti Termini e condizioni, saremo responsabili solo per eventuali perdite subite di conseguenza nella misura in cui siano una conseguenza prevedibile per entrambi nel momento in cui utilizzi il Sito della Societ\u00e0. La nostra responsabilit\u00e0 non includer\u00e0 in ogni caso questioni aziendali come la perdita di dati, la perdita di profitti o l'interruzione dell'attivit\u00e0. Questa clausola non limiter\u00e0 n\u00e9 influir\u00e0 sulla nostra responsabilit\u00e0 derivante dal fatto che qualsiasi prodotto venduto attraverso il Sito della Societ\u00e0 sia ritenuto non sicuro o se qualcosa fatto da noi per negligenza provochi la morte o lesioni personali.\r\n\r\n<strong>Siti web di terze parti<\/strong>\r\nLa Societ\u00e0 non si assume alcuna responsabilit\u00e0 per il contenuto di qualsiasi sito a cui vi sia collegato un link ipertestuale tramite questo sito. I link sono forniti \"come tali\" senza alcuna garanzia, esplicita o implicita, per le informazioni fornite al loro interno. La fornitura di un collegamento non implica alcuna approvazione del relativo sito da parte della Societ\u00e0.\r\n\r\n<strong>Invio di e-mail<\/strong>\r\nLa prova dell'invio di un'e-mail non \u00e8 una prova di ricezione. La Societ\u00e0 declina ogni responsabilit\u00e0 per la mancata ricezione delle informazioni trasmesse tramite questo sito.\r\n\r\n<strong>Norme applicabili<\/strong>\r\nQuesto sito Web \u00e8 controllato dalla Societ\u00e0 dai suoi uffici locati in Inghilterra. Accedendo a questo sito, accetti che tutte le questioni relative al tuo accesso o utilizzo di questo sito siano regolate dalla normativa inglese in materia; e accetti di sottometterti alla giurisdizione dei tribunali inglesi in merito a tali questioni.\r\n\r\n<strong>Uso internazionale<\/strong>\r\nLa Societ\u00e0 non garantisce che i materiali su questo sito siano appropriati o disponibili per l'uso in altri luoghi e l'accesso da territori in cui il loro contenuto \u00e8 illegale \u00e8 proibito. Chiunque scelga di accedere a questo sito da altre localit\u00e0 lo fa di propria iniziativa ed \u00e8 responsabile del rispetto delle leggi locali.\r\n\r\n<strong>Il tuo utilizzo del sito aziendale<\/strong>\r\nNon puoi utilizzare il Sito aziendale per nessuno dei seguenti scopi:\r\n1. Disseminare qualsiasi materiale illegale, molesto, calunnioso, offensivo, minaccioso, dannoso, volgare, assente o in qualche modo discutibile o parimenti violare qualsiasi legge\r\n2. Diffondere materiale che incoraggi una condotta che costituisce un reato penale o che violi in altro modo qualsiasi legge, regolamento o codice di condotta applicabile\r\n3. Interferire con l'uso o il godimento del Sito della Societ\u00e0 da parte di terzi\r\n4. Il download, creazione, ripubblicazione, riproduzione, trasmissione o archiviazione o altro uso di copie elettroniche di materiali protetti da copyright come file autonomi senza l'autorizzazione del proprietario\r\n\r\nSarai responsabile delle nostre perdite e dei costi derivanti dalla violazione di questa clausola.\r\n\r\n<strong>Varie<\/strong>\r\nNon puoi trasferire nessuno dei tuoi diritti a nessun'altra persona ai sensi dei presenti Termini e condizioni. Potremmo trasferire i nostri diritti a un'altra azienda, ai sensi dei presenti Termini e condizioni, nel momento in cui riteniamo ragionevolmente che i tuoi diritti non siano coinvolti. In caso di violazione dei presenti Termini e condizioni e la Societ\u00e0 scelga di ignorarlo, la Societ\u00e0 avr\u00e0 comunque il diritto di utilizzare i propri diritti e misure correttive in un secondo momento o in qualsiasi altra situazione in cui si violano i Termini e le condizioni.\r\n\r\nLa Societ\u00e0 non sar\u00e0 responsabile per qualsiasi violazione di questi Termini e Condizioni causata da circostanze al di fuori del suo ragionevole controllo. Il sito della societ\u00e0 \u00e8 di propriet\u00e0 e gestito da HH Associates Ltd. Sede legale: Grove House, Guildford Rd., Leatherhead, Surrey, SM1 2AE, numero di registrazione nel Regno Unito: 2671533. In caso di domande, si prega di contattare: <a href=\"mailto:info@www.hhglobal.com\" target=\"_blank\" rel=\"noopener\">info@www.hhglobal.com<\/a>\r\n\r\nTermini e condizioni generali di acquisto\r\nI presenti termini e condizioni e qualsiasi altro documento a cui si fa riferimento nel presente si applicano a qualsiasi Ordine di acquisto di beni o servizi effettuato dal soggetto HH Global al fornitore. HHG non accetta modifiche a questi T&amp;C se non concordate per iscritto. Nessuna dichiarazione del Fornitore influir\u00e0 sui presenti T&amp;C. I termini di fornitura o il preventivo standard o stampati del fornitore non si applicano a questo ordine di acquisto.\r\n\r\n<strong>Definizioni:<\/strong>\r\n1.1 \"Informazioni riservate\" indica qualsiasi informazione, comunque trasmessa o presentata, relativa all'attivit\u00e0, agli affari, alle operazioni, ai clienti, ai processi, ai budget, alle politiche dei prezzi, alle informazioni sui prodotti, alle strategie, agli sviluppi, ai segreti commerciali, al know-how, al personale e ai fornitori di HHG, unitamente a tutte le informazioni ricavate dal Fornitore da tali informazioni e qualsiasi altra informazione che HHG ritenga riservata al momento della divulgazione o che dovrebbe ragionevolmente essere considerata riservata dal Fornitore;\r\n\r\n1.2 \"Cliente finale\" indica il cliente di HHG che ha stipulato o intende stipulare un contratto con HHG per la fornitura di beni e servizi;\r\n\r\n1.3 \"Contratto con il cliente finale\" indica il contratto effettivo o proposto tra HHG e un cliente finale;\r\n\r\n1.4 \u201cBeni\u201d e \u201cServizi\u201d indicano i prodotti ei servizi che HHG pu\u00f2 acquistare dal Fornitore e che saranno dettagliati in ciascun ordine di acquisto; 1.5 \"Ordine di acquisto\" o \"PO\" indica l'ordine di acquisto emesso da HHG al Fornitore per l'acquisto di Beni e Servizi;\r\n\r\n1.6 \"Specifiche\" indica le condizioni necessarie dei Beni e Servizi ai sensi di ciascun ordine di acquisto. Oltre alle Specifiche scritte, queste possono includere qualsiasi campione fornito dal Fornitore.\r\n<strong>\r\n2. Preventivi e Prezzi:<\/strong>\r\n2.1 HHG comunicher\u00e0 al Fornitore un numero d'ordine di acquisto per telefono, fax o e-mail. Il Fornitore deve includere il numero dell'ordine di acquisto su ogni foglio di imballaggio, fattura e ogni altra comunicazione relativa a tale ordine di acquisto.\r\n\r\n2.2 I prezzi quotati includeranno i costi di imballaggio, assicurazione, dazi doganali e altri dazi o tasse e il trasporto dei Beni nel luogo specificato nelle Specifiche, salvo quanto diversamente indicato nel preventivo dal Fornitore. 2.3 Tutti i prezzi indicati dal Fornitore sono da considerarsi tasse escluse.\r\n\r\n2.4 Una volta che HHG emette un ordine di acquisto basato su un preventivo, i prezzi nel preventivo vengono fissati per tale ordine di acquisto, a meno che le parti non accettino di modificare il preventivo e\/o il prezzo, nel qual caso HHG invier\u00e0 un ordine di acquisto modificato al Fornitore.\r\n<strong>\r\n3. Qualit\u00e0 e Garanzia:<\/strong>\r\n3.1 Il Fornitore dovr\u00e0 fabbricare, imballare, fornire e consegnare i Beni e i Servizi come segue:\r\na. Beni e servizi devono essere conformi alle specifiche dettagliate per ciascun ordine di acquisto e devono corrispondere a qualsiasi campione approvato da HHG.\r\nb. I Beni e i Servizi devono essere almeno di qualit\u00e0 standard, privi di qualsiasi difetto, quali i difetti di progettazione, materiale e fabbricazione, e adatti all'uso previsto del Cliente finale. Il Fornitore conferma di essere a conoscenza dell'uso previsto del Cliente finale.\r\nc. Beni e servizi saranno liberi da qualsiasi diritto di terzi e devono essere conformi a tutte le leggi applicabili e agli standard e alle pratiche del settore generalmente accettati.\r\n\r\n3.2 Il Fornitore eseguir\u00e0 i Servizi con abilit\u00e0, professionalit\u00e0 e tecnologia all'avanguardia che generalmente ci si aspetta sul mercato da un fornitore di beni e servizi del tipo coperto dal presente ordine d\u2019acquisto.\r\n\r\n3.3 Il Fornitore fornisce una garanzia di tre mesi dalla data di consegna per i materiali stampati e di dodici mesi dalla data di consegna per tutti gli altri Beni. Se durante il periodo di garanzia viene scoperto un difetto della Merce, il Fornitore dovr\u00e0 correggere tali difetti o sostituire la Merce gratuitamente.\r\n\r\n<strong>4. Consegna e Accettazione:<\/strong>\r\n4.1 La consegna puntuale dei Beni e dei Servizi \u00e8 un fattore critico negli Accordi con il Cliente Finale tra HHG e i suoi Clienti Finali. Pertanto, il Fornitore deve consegnare tutti i Beni e Servizi nella quantit\u00e0 corretta alla data e nel luogo indicati nelle Specifiche o nell'Ordine di acquisto o come richiesto da HHG con ragionevole preavviso. Il Fornitore rimborser\u00e0 a HHG , previo risarcimento, in caso di qualsiasi ritardo nella consegna rispetto alla scadenza concordata.\r\n\r\n4.2 Il Fornitore assicurer\u00e0 le Merci per l'intero valore di sostituzione fino alla consegna. Il Fornitore garantisce la propriet\u00e0 di tutti i Beni venduti e si assume il rischio di perdita o danni agli articoli acquistati ai sensi del presente Ordine di acquisto fino alla consegna-in conformit\u00e0 con il presente Ordine di acquisto presso il punto di consegna di HHG specificato in questo Ordine di acquisto o come richiesto e, a tale consegna, il titolo dello stesso passer\u00e0 a HHG. Il passaggio di propriet\u00e0 non costituisce accettazione degli articoli da parte di HHG.\r\n\r\n4.3 HHG e, ove applicabile, il Cliente finale, godranno di un periodo di accettazione per ispezionare i Beni o i Servizi e per notificare eventuali difetti al Fornitore. Il Periodo di accettazione \u00e8 di 30 giorni dalla data di consegna.\r\n\r\n<strong>5. Pagamento e Fatturazione:<\/strong>\r\n5.1 Salvo diversamente concordato in un ordine di acquisto, il Fornitore fatturer\u00e0 HHG solo dopo la consegna, dei beni o servizi ai sensi dell'ordine di acquisto, nel luogo specificato e successivamente alla loro accettazione ai sensi della clausola 4.\r\n\r\n5.2 Se non diversamente concordato in un PO, HHG pagher\u00e0 la fattura del Fornitore entro novanta giorni dalla data di ricevimento di una fattura valida dal Fornitore, se sono soddisfatti i seguenti requisiti:\r\na. La fattura fa riferimento al numero dell'ordine di acquisto;\r\nb. La fattura \u00e8 indirizzata al soggetto HHG, che ne ha emesso l'ordine di acquisto;\r\nc. Il valore della fattura corrisponde al valore dell'ordine di acquisto ed \u00e8 nella stessa valuta; e d. Il Fornitore ha fornito a HHG la prova di consegna elettronica o qualsiasi altra prova di consegna come concordato separatamente tra HHG e il Fornitore.\r\n\r\n5.3 Se HHG contesta qualsiasi fattura o altra dichiarazione di importi dovuti, HHG informer\u00e0 il Fornitore per iscritto. Le parti negozieranno in buona fede per risolvere tempestivamente la controversia. Il Fornitore dovr\u00e0 fornire tutte le prove ragionevolmente necessarie per verificare la fattura contestata o la richiesta di pagamento. Gli obblighi del Fornitore di fornire i Beni e i Servizi non saranno influenzati da alcuna controversia sul pagamento.\r\n\r\n<strong>6. Diritti di propriet\u00e0 intellettuale:<\/strong>\r\nIl Fornitore garantisce che tutti i Beni e Servizi forniti ai sensi del presente PO non si traducano in violazione di brevetti, diritti d'autore, segreti commerciali, nomi commerciali, marchi di fabbrica o marchi di servizio di terze parti o altri diritti di propriet\u00e0 . Tutti i diritti di propriet\u00e0 intellettuale nei beni e servizi creati appositamente per HHG apparterranno a HHG e HHG pu\u00f2 assegnare tali diritti di propriet\u00e0 intellettuale al cliente finale. Altri DPI contenuti nei Beni e Servizi rimarranno i DPI del Fornitore. Tuttavia, il Fornitore concede a HHG e al Cliente finale una licenza mondiale, esente da royalty, non esclusiva e perpetua per utilizzare, copiare, modificare e distribuire tali DPI come parte dei Beni e Servizi. Il Fornitore si impegna a fornire a HHG tutta l'assistenza ragionevolmente richiesta da HHG per perfezionare i diritti descritti nel presente documento, incluso l'ottenimento di tutte le assegnazioni e rinunce ai diritti morali necessarie o appropriate per conferire i diritti di propriet\u00e0 intellettuale su tali materiali in HHG.\r\n\r\n<strong>7. Subappalto e Affidamento:<\/strong>\r\nIl Fornitore non ceder\u00e0 il presente PO o alcun diritto qui di seguito, n\u00e9 delegher\u00e0 alcun compito, n\u00e9 subappalter\u00e0 alcun lavoro, senza la previa approvazione scritta di HHG. Il prezzo indicato dal Fornitore include il prezzo di qualsiasi bene o servizio ottenuto da qualsiasi subappaltatore o fornitore al Fornitore, salvo diversamente concordato in anticipo da HHG. Il Fornitore rimarr\u00e0 pienamente responsabile per tutto il lavoro svolto da tali terze parti e indennizzare e manlevare HHG per qualsiasi pagamento richiesto a tali parti.\r\n\r\n<strong>8. Riservatezza:<\/strong>\r\n8.1 Ad eccezione di quanto stabilito nella presente clausola, o laddove la divulgazione sia espressamente consentita altrove nei presenti T&amp;C, il Fornitore utilizzer\u00e0 le Informazioni riservate di HHG solo per raggiungere gli scopi contemplati nei presenti T&amp;C e tratter\u00e0 le Informazioni riservate di HHG come tali; non divulgher\u00e0 le informazioni riservate di HHG a qualsiasi altra persona senza il previo consenso scritto di HHG.\r\n\r\n8.2 Il fornitore pu\u00f2 divulgare le informazioni riservate di HHG solo al\r\na) personale del Fornitore che \u00e8 coinvolto nella fornitura dei Servizi e che necessita conoscere tali informazioni. Il Fornitore assicurer\u00e0 che il proprio personale sia a conoscenza e rispetti tali obblighi di riservatezza; e\r\nb) ai revisori dei conti del Fornitore, ai consulenti professionali e a qualsiasi tribunale o organismo di regolamentazione che abbia il diritto statutario o regolamentare di richiedere e ricevere tali informazioni.\r\n\r\n8.3 HHG \u00e8 autorizzata a divulgare le Informazioni riservate del Fornitore alle sue affiliate e ai loro dipendenti e al Cliente finale per consentire la fornitura di Beni e Servizi e parimenti per soddisfare gli scopi di questi T&amp;C.\r\n\r\n8.4 Le parti riconoscono che i rimedi legali per qualsiasi violazione di codesta clausola potrebbero non essere adeguati e che HHG avr\u00e0 il diritto di chiedere un equo risarcimento per qualsiasi violazione di questo tipo, incluso un provvedimento ingiuntivo.\r\n\r\n<strong>9. Indennizzo e limitazione di responsabilit\u00e0.<\/strong> Il Fornitore dovr\u00e0 difendere, indennizzare e manlevare HHG, le sue affiliate ed i suoi azionisti, direttori, funzionari, dipendenti e agenti da e contro qualsiasi causa, rivendicazione, azione, responsabilit\u00e0, perdita, danno, giudizio, costo e spesa derivanti da o risultanti dalla violazione da parte del Fornitore di qualsiasi termine e\/o condizione del presente Contratto. IN NESSUN CASO HHG SAR\u00c0 RESPONSABILE NEI CONFRONTI DEL FORNITORE O TERZE PARTI PER DANNI CONSEQUENZIALI, ACCIDENTALI, INDIRETTI, ESEMPLARI, SPECIALI O PUNITIVI DERIVANTI DA VIOLAZIONE CONTRATTUALE, ILLECITO O ALTRO, INDIPENDENTEMENTE DALLA PREVEDIBILIT\u00c0 DI TALI DANNI E SE HHG SIA STATA O MENO AVVISATA DELLA POSSIBILIT\u00c0 DI TALI DANNI.\r\n\r\n<strong>10. Codice di condotta:<\/strong> Il Fornitore si impegna a rispettare rigorosamente il Codice di condotta dei fornitori di HH Global in ogni momento. Il Fornitore riconosce di aver ricevuto una copia del Codice nel momento dell\u2019emissione di un ordine di acquisto da parte di HHG nei confronti del Fornitore e con il Fornitore ad averne letto e compreso il Codice.\r\n\r\n<strong>11. Legge applicabile:<\/strong> I presenti T&amp;C saranno regolati e interpretati in conformit\u00e0 con le leggi del paese in cui il soggetto HHG, che effettua l'Ordine di acquisto, ha la sua sede di attivit\u00e0."},{"acf_fc_layout":"contact_form","scroll_to_link":"","title":"Contattaci"}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terms + Conditions - HH Global<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hhglobal.com\/it\/terms-conditions\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terms + Conditions - HH Global\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hhglobal.com\/it\/terms-conditions\/\" \/>\n<meta property=\"og:site_name\" content=\"HH Global\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-16T15:30:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/terms-conditions\\\/\",\"url\":\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/terms-conditions\\\/\",\"name\":\"Terms + Conditions - HH Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/#website\"},\"datePublished\":\"2022-05-18T09:51:38+00:00\",\"dateModified\":\"2024-01-16T15:30:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/terms-conditions\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/terms-conditions\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/terms-conditions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terms + Conditions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/\",\"name\":\"HH Global\",\"description\":\"The global, tech-enabled creative production and procurement partner.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/#organization\",\"name\":\"HH Global\",\"url\":\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hhglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo-white.svg\",\"contentUrl\":\"https:\\\/\\\/www.hhglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo-white.svg\",\"width\":77,\"height\":18,\"caption\":\"HH Global\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hhglobal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terms + Conditions - HH Global","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hhglobal.com\/it\/terms-conditions\/","og_locale":"it_IT","og_type":"article","og_title":"Terms + Conditions - HH Global","og_url":"https:\/\/www.hhglobal.com\/it\/terms-conditions\/","og_site_name":"HH Global","article_modified_time":"2024-01-16T15:30:01+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hhglobal.com\/it\/terms-conditions\/","url":"https:\/\/www.hhglobal.com\/it\/terms-conditions\/","name":"Terms + Conditions - HH Global","isPartOf":{"@id":"https:\/\/www.hhglobal.com\/it\/#website"},"datePublished":"2022-05-18T09:51:38+00:00","dateModified":"2024-01-16T15:30:01+00:00","breadcrumb":{"@id":"https:\/\/www.hhglobal.com\/it\/terms-conditions\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hhglobal.com\/it\/terms-conditions\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hhglobal.com\/it\/terms-conditions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hhglobal.com\/it\/"},{"@type":"ListItem","position":2,"name":"Terms + Conditions"}]},{"@type":"WebSite","@id":"https:\/\/www.hhglobal.com\/it\/#website","url":"https:\/\/www.hhglobal.com\/it\/","name":"HH Global","description":"The global, tech-enabled creative production and procurement partner.","publisher":{"@id":"https:\/\/www.hhglobal.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hhglobal.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hhglobal.com\/it\/#organization","name":"HH Global","url":"https:\/\/www.hhglobal.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hhglobal.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.hhglobal.com\/wp-content\/uploads\/2023\/12\/logo-white.svg","contentUrl":"https:\/\/www.hhglobal.com\/wp-content\/uploads\/2023\/12\/logo-white.svg","width":77,"height":18,"caption":"HH Global"},"image":{"@id":"https:\/\/www.hhglobal.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hhglobal.com\/it\/wp-json\/wp\/v2\/pages\/6903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hhglobal.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hhglobal.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hhglobal.com\/it\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hhglobal.com\/it\/wp-json\/wp\/v2\/comments?post=6903"}],"version-history":[{"count":0,"href":"https:\/\/www.hhglobal.com\/it\/wp-json\/wp\/v2\/pages\/6903\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hhglobal.com\/it\/wp-json\/wp\/v2\/media?parent=6903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}